{"id":19872,"date":"2026-01-09T11:40:20","date_gmt":"2026-01-09T17:40:20","guid":{"rendered":"https:\/\/iglesiaortodoxa.org.mx\/informacion\/?p=19872"},"modified":"2026-01-09T11:35:34","modified_gmt":"2026-01-09T17:35:34","slug":"cuarto-dia-de-la-fiesta-de-la-epifania-del-senor-martir-poliecto-de-melitene-en-armenia","status":"publish","type":"post","link":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/2026\/01\/cuarto-dia-de-la-fiesta-de-la-epifania-del-senor-martir-poliecto-de-melitene-en-armenia\/","title":{"rendered":"Cuarto d\u00eda de la fiesta de la Epifan\u00eda del Se\u00f1or; M\u00e1rtir Poliecto de Melitene en Armenia"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"size-full wp-image-19863 aligncenter\" src=\"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/\/bautismo-de-Cristo.jpg\" alt=\"\" width=\"211\" height=\"262\" srcset=\"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/bautismo-de-Cristo.jpg 211w, http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/bautismo-de-Cristo-141x175.jpg 141w\" sizes=\"(max-width: 211px) 100vw, 211px\" \/><\/p>\n<p style=\"text-align: justify;\">La fiesta de la Epifan\u00eda del Se\u00f1or se extiende del 6 hasta el 14 de enero. Varios de los himnos propios de la fiesta se siguen cantando en los servicios de V\u00edsperas y Maitines.<\/p>\n<h4 style=\"text-align: justify;\"><u>Tropario, tono 1<\/u><\/h4>\n<p style=\"text-align: justify;\">Al bautizarte, oh Se\u00f1or, en el Jord\u00e1n, * se manifest\u00f3 la adoraci\u00f3n a la Trinidad, * pues la voz del Padre dio testimonio de ti * nombr\u00e1ndote su Hijo amado; * y el Esp\u00edritu, en forma de paloma, * confirm\u00f3 la certeza de la palabra. * \u00a1T\u00fa, que te has revelado e iluminado al mundo, * oh Cristo Dios, gloria a ti!<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/music.youtube.com\/watch?v=tfiVS0HOIks&amp;si=iSb1VN37eZmK5RT9\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-19840\" src=\"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/\/youtub-3.png\" alt=\"\" width=\"175\" height=\"61\" \/><\/a><\/p>\n<h4 style=\"text-align: justify;\"><u>Condaquio Tono 4<\/u><\/h4>\n<p style=\"text-align: justify;\">\u00a0Te has revelado hoy * al universo, * y tu luz, oh Cristo Dios, * ha fulgurado sobre nosotros * que te alabamos con comprensi\u00f3n: * \u00a1te has manifestado, * oh Luz inaccesible!<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/music.youtube.com\/watch?v=untE_ah6lTM&amp;si=JZwVGhajqPUJJEoJ\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-19840\" src=\"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/\/youtub-3.png\" alt=\"\" width=\"175\" height=\"61\" \/><\/a><\/p>\n<h3>M\u00e1rtir Poliecto de Melitene<\/h3>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-19873 aligncenter\" src=\"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/\/san-poliecto-213x300.jpg\" alt=\"\" width=\"213\" height=\"300\" srcset=\"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/san-poliecto-213x300.jpg 213w, http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/san-poliecto-125x175.jpg 125w, http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/san-poliecto.jpg 249w\" sizes=\"(max-width: 213px) 100vw, 213px\" \/><\/p>\n<p style=\"text-align: justify;\">San Poliecto fue el primer m\u00e1rtir en la ciudad \u00e1rmenia de Melitene. Era soldado bajo el emperador Decio (249-251) y sufri\u00f3 por Cristo bajo el emperador Valeriano (253-259). El santo era amigo de Nearcos, un soldado compa\u00f1ero y cristiano firme. San Poliecto aunque llevaba una vida virtuosa, continuaba como pagano.<\/p>\n<p style=\"text-align: justify;\">Cuando empez\u00f3 la persecuci\u00f3n de los cristianos Nearcos dijo a Poliecto, &#8220;Amigo, nos van a separar porque me van a torturar, y tu desgraciadamente vas a renunciar nuestra amistad&#8221;. Poliecto le dijo que hab\u00eda visto a Jesucristo en un sue\u00f1o y que \u00c9l le quito su capa militar sucia y le visti\u00f3 en una vestimenta resplandeciente. Dijo, &#8220;Ahora estoy listo para servir al Se\u00f1or Jesucristo&#8221;.<\/p>\n<p style=\"text-align: justify;\">Mientras que ard\u00eda con celo, san Poliecto se fue a la plaza y rompi\u00f3 el edicto de Decio mandando a todos adorar a los \u00eddolos. Unos momentos despu\u00e9s, se encontr\u00f3 con una procesi\u00f3n cargando doce \u00eddolos por las calles de la ciudad. El tir\u00f3 los \u00eddolos al suelo pisote\u00e1ndolos.<\/p>\n<p style=\"text-align: justify;\">Su suegro, el magistrado F\u00e9lix, responsable de reforzar el decreto imperial, se asust\u00f3 al saber lo que hizo san Poliecto y le dijo que ten\u00eda que morir. Dijo el magistrado F\u00e9lix, &#8220;Vete y desp\u00eddete de tu esposa y tus hijos&#8221;. Su esposa, Paulina, vino y le rogaba con l\u00e1grimas que renunciara a Cristo. Su suegro F\u00e9lix tambi\u00e9n lloraba, pero san Poliecto permaneci\u00f3 firme en su determinaci\u00f3n de sufrir por Jesucristo.<\/p>\n<p style=\"text-align: justify;\">Con alegr\u00eda baj\u00f3 la cabeza bajo la espada del verdugo y fue bautizado con su propia sangre. Durante el reinado de san Constantino construyeron una iglesia en Melitene para honrar san Poliecto. Muchos milagros sucedieron por las intercesiones del santo. En la misma iglesia los padres de San Eutimio el Grande (20 de enero) rezaron con fervor por un hijo y naci\u00f3 esta gran lumbrera de la Ortodoxia en el a\u00f1o 376 con la ayuda del santo M\u00e1rtir Poliecto.<\/p>\n<h4 style=\"text-align: justify;\"><u>Tropario tono 4, del com\u00fan de Santos M\u00e1rtires<\/u><\/h4>\n<p style=\"text-align: justify;\">Tu m\u00e1rtir, oh Se\u00f1or, * ha obtenido de ti * corona de incorrupci\u00f3n * en su lucha, Dios nuestro. * Al tener, pues, tu fuerza, * ha vencido a tiranos * y aplastado de los demonios * su abatida insolencia. * Por sus intercesiones, oh Cristo Dios, * salva nuestras almas.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/music.youtube.com\/watch?v=7xLtA5gdqP0&amp;si=03CS1Qvr2jatG8IS\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-19840\" src=\"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/\/youtub-3.png\" alt=\"\" width=\"175\" height=\"61\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La fiesta de la Epifan\u00eda del Se\u00f1or se extiende del 6 hasta el 14 de enero. Varios de los himnos propios de la fiesta se siguen cantando en los servicios de V\u00edsperas y Maitines. Tropario, tono 1 Al bautizarte, oh Se\u00f1or, en el Jord\u00e1n, * se manifest\u00f3 la adoraci\u00f3n a la Trinidad, * pues la [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"categories":[75,16],"tags":[],"_links":{"self":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts\/19872"}],"collection":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/comments?post=19872"}],"version-history":[{"count":3,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts\/19872\/revisions"}],"predecessor-version":[{"id":21561,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts\/19872\/revisions\/21561"}],"wp:attachment":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/media?parent=19872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/categories?post=19872"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/tags?post=19872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}