{"id":18539,"date":"2024-06-27T00:00:02","date_gmt":"2024-06-27T06:00:02","guid":{"rendered":"https:\/\/iglesiaortodoxa.org.mx\/informacion\/?p=18539"},"modified":"2024-06-19T12:22:27","modified_gmt":"2024-06-19T18:22:27","slug":"27-san-sanson-el-hospitalario","status":"publish","type":"post","link":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/2024\/06\/27-san-sanson-el-hospitalario\/","title":{"rendered":"San Sans\u00f3n el Hospitalario"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"size-medium wp-image-18540 aligncenter\" src=\"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/\/0627sampsonhospitable2-172x300.jpg\" alt=\"\" width=\"172\" height=\"300\" srcset=\"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/0627sampsonhospitable2-172x300.jpg 172w, http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/0627sampsonhospitable2-101x175.jpg 101w, http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/0627sampsonhospitable2.jpg 500w\" sizes=\"(max-width: 172px) 100vw, 172px\" \/><\/p>\n<p style=\"text-align: justify;\">San Sans\u00f3n naci\u00f3 en Roma, hijo de padres ricos, pero devotos y virtuosos. Recibi\u00f3 una excelente educaci\u00f3n, estudiando filosof\u00eda y medicina, entre otras materias. Desde su m\u00e1s tierna infancia vivi\u00f3 una vida cristiana ejemplar. Tras la muerte de sus padres transform\u00f3 la finca familiar en una cl\u00ednica para enfermos. Se corri\u00f3 la voz de sus habilidades curativas, y tanta gente acudi\u00f3 a \u00e9l que tuvo que contratar personal para atender al creciente n\u00famero de personas que buscaban su ayuda. Cuando tuvo el personal adecuado, don\u00f3 toda su riqueza a la cl\u00ednica y se content\u00f3 con vivir en la pobreza.<\/p>\n<p style=\"text-align: justify;\">\nSan Sans\u00f3n fue a Constantinopla, donde esperaba pasar el resto de su vida en el ascetismo. Sin embargo, descubri\u00f3 que hab\u00eda tanta necesidad de su habilidad en Constantinopla como la hab\u00eda habido en Roma. Compr\u00f3 una casa modesta y comenz\u00f3 a tratar a los enfermos. Dios bendijo la obra de San Sans\u00f3n y le concedi\u00f3 la gracia de obrar milagros. San\u00f3 a los enfermos no s\u00f3lo con su habilidad m\u00e9dica, sino tambi\u00e9n como alguien lleno de la gracia de Dios. Las noticias de San Sans\u00f3n se difundieron r\u00e1pidamente por todas partes.<\/p>\n<p style=\"text-align: justify;\">\nSu piedad y amor por el pr\u00f3jimo llamaron la atenci\u00f3n del Patriarca Menas de Constantinopla (25 de agosto), quien lo orden\u00f3 al santo sacerdocio. Cuando el emperador Justiniano enferm\u00f3 y sus m\u00e9dicos no pudieron brindarle ning\u00fan alivio, el patriarca Menas sugiri\u00f3 que enviara a buscar a Sans\u00f3n, quien cur\u00f3 al emperador. Justiniano le ofreci\u00f3 oro y plata como muestra de su gratitud, pero el santo se neg\u00f3, diciendo que ya hab\u00eda regalado todas sus riquezas. En cambio, le pidi\u00f3 a Justiniano que construyera un hospicio para viajeros.<\/p>\n<p style=\"text-align: justify;\">\nSan Sans\u00f3n repos\u00f3 tranquilamente, tras una breve enfermedad, en el a\u00f1o 530 en una edad avanzada. Fue enterrado en la iglesia de San Mocio, construida por San Constantino el Grande.<\/p>\n<p style=\"text-align: justify;\">\nEn la tumba de San Sans\u00f3n se han producido muchos milagros de curaci\u00f3n.<\/p>\n<h4>Tono 8 (plagal del tono 4)<\/h4>\n<p style=\"text-align: justify;\">\nEn tu paciencia has logrado tu recompensa, oh padre just\u00edsimo, * perseverando asiduamente en la oraci\u00f3n, * amando a los pobres y atendiendo sus necesidades. * Intercede ante Cristo Dios, dichoso Sans\u00f3n iluminado, * para que salve nuestras almas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Sans\u00f3n naci\u00f3 en Roma, hijo de padres ricos, pero devotos y virtuosos. Recibi\u00f3 una excelente educaci\u00f3n, estudiando filosof\u00eda y medicina, entre otras materias. Desde su m\u00e1s tierna infancia vivi\u00f3 una vida cristiana ejemplar. Tras la muerte de sus padres transform\u00f3 la finca familiar en una cl\u00ednica para enfermos. Se corri\u00f3 la voz de sus [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"categories":[124,3,16],"tags":[],"_links":{"self":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts\/18539"}],"collection":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/comments?post=18539"}],"version-history":[{"count":4,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts\/18539\/revisions"}],"predecessor-version":[{"id":18670,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts\/18539\/revisions\/18670"}],"wp:attachment":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/media?parent=18539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/categories?post=18539"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/tags?post=18539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}