{"id":16018,"date":"2020-01-16T00:00:56","date_gmt":"2020-01-16T06:00:56","guid":{"rendered":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/?p=16018"},"modified":"2020-01-19T01:03:37","modified_gmt":"2020-01-19T07:03:37","slug":"veneracion-de-las-cadenas-del-santo-y-glorioso-apostol-pedro","status":"publish","type":"post","link":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/2020\/01\/veneracion-de-las-cadenas-del-santo-y-glorioso-apostol-pedro\/","title":{"rendered":"Veneraci\u00f3n de las Cadenas del Santo y Glorioso Ap\u00f3stol Pedro"},"content":{"rendered":"<h3><img loading=\"lazy\" class=\"alignnone  wp-image-16019 aligncenter\" src=\"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/\/16-cade.jpg\" alt=\"\" width=\"187\" height=\"310\" srcset=\"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/16-cade.jpg 241w, http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/16-cade-181x300.jpg 181w, http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/16-cade-105x175.jpg 105w\" sizes=\"(max-width: 187px) 100vw, 187px\" \/><\/h3>\n<h3 style=\"text-align: center;\">Veneraci\u00f3n de las Cadenas del Santo y Glorioso Ap\u00f3stol Pedro<\/h3>\n<h3 style=\"text-align: center;\">16 de Enero<\/h3>\n<p style=\"text-align: justify;\">\nSan Pedro es conmemorado en este d\u00eda a causa de las cadenas con las que fue atado por el inicuo Herodes, y que durante la aparici\u00f3n del \u00e1ngel en la prisi\u00f3n cayeron de sus manos (cfr. Hechos 12:7). Estas cadenas fueron preservadas por los cristianos tanto en memoria de este gran Ap\u00f3stol como por su poder de sanidad, pues muchos enfermos eran sanados al tocarlas, tal como ocurr\u00eda con los pa\u00f1uelos del Ap\u00f3stol Pablo (cfr. Hechos 19:12). De esto, la Iglesia de Cristo ha aprendido a mostrar reverencia y piedad no solo a las reliquias de los cuerpos, sino tambi\u00e9n a las vestimentas de los santos de Dios.<br \/>\nSan Juvenal, patriarca de Jerusal\u00e9n, dio estas cadenas como regalo a la Emperatriz Eudoxia, la esposa del Emperador Teodosio el Joven, que hab\u00eda sido exiliada. Esta las dividi\u00f3 en dos partes, enviando una a la iglesia del santo Ap\u00f3stol en Constantinopla, y la otra a su hija, la Emperatriz Eudoxia, esposa de Valentiniano en Roma. Eudoxia construy\u00f3 all\u00ed la Iglesia de san Pedro y deposit\u00f3 all\u00ed estas cadenas, junto con aquellas con las cuales Pedro fue atado antes de su ejecuci\u00f3n bajo el Emperador Ner\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Tropario, tono 2<br \/>\nSin salir de Roma, viniste a nosotros por las preciosas cadenas que llevabas puestas. \u00a1Oh, Pr\u00edncipe de los ap\u00f3stoles! Y vener\u00e1ndolas con fe, rogamos: Por tus intercesiones ante Dios, conc\u00e9denos la gran misericordia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Veneraci\u00f3n de las Cadenas del Santo y Glorioso Ap\u00f3stol Pedro 16 de Enero San Pedro es conmemorado en este d\u00eda a causa de las cadenas con las que fue atado por el inicuo Herodes, y que durante la aparici\u00f3n del \u00e1ngel en la prisi\u00f3n cayeron de sus manos (cfr. Hechos 12:7). Estas cadenas fueron preservadas [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"categories":[75,16],"tags":[],"_links":{"self":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts\/16018"}],"collection":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/comments?post=16018"}],"version-history":[{"count":1,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts\/16018\/revisions"}],"predecessor-version":[{"id":16020,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts\/16018\/revisions\/16020"}],"wp:attachment":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/media?parent=16018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/categories?post=16018"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/tags?post=16018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}