{"id":15985,"date":"2020-01-15T00:00:22","date_gmt":"2020-01-15T06:00:22","guid":{"rendered":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/?p=15985"},"modified":"2020-01-13T23:26:21","modified_gmt":"2020-01-14T05:26:21","slug":"santos-monjes-pablo-de-tebas-y-juan-calabita-de-constantinopla","status":"publish","type":"post","link":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/2020\/01\/santos-monjes-pablo-de-tebas-y-juan-calabita-de-constantinopla\/","title":{"rendered":"Santos Monjes Pablo de Tebas y Juan Calabita de Constantinopla"},"content":{"rendered":"<h3><img loading=\"lazy\" class=\" wp-image-15986 aligncenter\" src=\"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/\/Santos-Monjes-Pablo-de-Tebas.png\" alt=\"\" width=\"178\" height=\"258\" srcset=\"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/Santos-Monjes-Pablo-de-Tebas.png 246w, http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/Santos-Monjes-Pablo-de-Tebas-207x300.png 207w, http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/Santos-Monjes-Pablo-de-Tebas-121x175.png 121w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/h3>\n<h3 style=\"text-align: center;\">Santos Monjes Pablo de Tebas<\/h3>\n<h3 style=\"text-align: center;\">15 de Enero<\/h3>\n<p>Nacido de padres ricos en el bajo Tebas en Egipto durante el reino del Emperador Decio, Pablo y una hermana suya heredaron todas las riquezas de sus padres. Mas su cu\u00f1ado, que era un id\u00f3latra, planeaba quedarse con la parte de la herencia que pertenec\u00eda a Pablo, as\u00ed que lo amenaz\u00f3 con denunciarlo como cristiano ante las autoridades si no le entregaba su parte de la herencia. Este infortunio, unido a los ejemplos de sacrificio propio de los m\u00e1rtires cristianos que Pablo hab\u00eda contemplado con sus propios ojos, lo movieron a dar su mitad de la herencia a su hermana y a retirarse al desierto, donde vivi\u00f3 en ascetismo hasta su muerte. Las alturas espirituales a las que lleg\u00f3 este gigante del monacato son atestiguadas nada menos que por san Antonio el Grande, quien visit\u00f3 a Pablo en una ocasi\u00f3n y vio como las bestias salvajes y las aves de cielo le serv\u00edan. Al regresar de esta visita, Antonio dijo a sus monjes: \u00abAy de m\u00ed, hijos m\u00edos, pues soy un monje falso y pecador, un monje s\u00f3lo en nombre. He visto a El\u00edas, a Juan en el desierto, a Pablo en el Para\u00edso!\u00bb. San Pablo vivi\u00f3 ciento trece a\u00f1os, y entr\u00f3 en paz a su descanso en el Se\u00f1or en el a\u00f1o 342 d. C.<\/p>\n<p>Tropario, tono 8<br \/>\nCon la efusi\u00f3n de tus l\u00e1grimas, regaste el desierto est\u00e9ril; y por los suspiros profundos, tus fatigas dieron frutos cien veces m\u00e1s, volvi\u00e9ndote un astro del universo, brillante con los milagros. \u00a1Oh nuestro justo padre Pablo, supl\u00edcale a Cristo Dios que salve nuestras almas!<\/p>\n<h3 style=\"text-align: center;\">\nSan Juan Calabita<\/h3>\n<p>Abandonando a sus padres y su cuantiosa fortuna, San Juan se retir\u00f3 del mundo a Gom\u00f3n del B\u00f3sforo, entre los monjes &#8220;vigilantes,&#8221; fundados por San Alejandro Akimetes. A los diecis\u00e9is a\u00f1os retorn\u00f3 a su casa disfrazado de mendigo y vivi\u00f3 de la caridad de sus padres, sin ser reconocido por ellos, en una choza pr\u00f3xima a su casa. El nombre de Calabita se deriva de la palabra griega &#8220;Kaliba,&#8221; que significa &#8220;choza.&#8221; Juan se santific\u00f3 ah\u00ed por la paciencia, la mansedumbre y la oraci\u00f3n. Se cuenta que, hall\u00e1ndose ya en el lecho de su muerte, revel\u00f3 su identidad a su madre, aduciendo como prueba el libro de los Evangelios empastado en oro que hab\u00eda usado de ni\u00f1o. El santo pidi\u00f3 que le sepultaran en la choza donde hab\u00eda vivido. As\u00ed se hizo, en efecto; pero sobre la choza se construy\u00f3 una iglesia.<\/p>\n<p>Tropario, tono 4<br \/>\nYa que con fervor anhelaste al Se\u00f1or desde tu juventud, dejaste el mundo con sus delicias y luchaste noblemente en valientes actos asc\u00e9ticos. Pusiste tu caba\u00f1a ante las puertas de tus padres; rompiste las trampas de los demonios, oh bendito Padre. Y, por lo tanto, encontrando a Cristo Dios has sido glorificado, oh Juan.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santos Monjes Pablo de Tebas 15 de Enero Nacido de padres ricos en el bajo Tebas en Egipto durante el reino del Emperador Decio, Pablo y una hermana suya heredaron todas las riquezas de sus padres. Mas su cu\u00f1ado, que era un id\u00f3latra, planeaba quedarse con la parte de la herencia que pertenec\u00eda a Pablo, [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"categories":[75,16],"tags":[],"_links":{"self":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts\/15985"}],"collection":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/comments?post=15985"}],"version-history":[{"count":1,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts\/15985\/revisions"}],"predecessor-version":[{"id":15987,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts\/15985\/revisions\/15987"}],"wp:attachment":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/media?parent=15985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/categories?post=15985"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/tags?post=15985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}