{"id":15532,"date":"2019-12-31T00:00:00","date_gmt":"2019-12-31T06:00:00","guid":{"rendered":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/?p=15532"},"modified":"2019-12-19T15:47:44","modified_gmt":"2019-12-19T21:47:44","slug":"santa-melania-la-joven-de-roma","status":"publish","type":"post","link":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/2019\/12\/santa-melania-la-joven-de-roma\/","title":{"rendered":"Santa Melania la Joven, de Roma"},"content":{"rendered":"<h3 style=\"text-align: center;\"><\/h3>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-15533 aligncenter\" src=\"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/\/Santa-Melania-la-Joven-de-Roma.png\" alt=\"\" width=\"178\" height=\"229\" srcset=\"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/Santa-Melania-la-Joven-de-Roma.png 178w, http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-content\/uploads\/Santa-Melania-la-Joven-de-Roma-136x175.png 136w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/p>\n<h3 style=\"text-align: center;\">Santa Melania la Joven, de Roma.<\/h3>\n<h3 style=\"text-align: center;\">31 de Diciembre<\/h3>\n<p>Santa Melania la Joven, que naci\u00f3 en 388, era la nieta de Santa Melania la Grande (8 de junio). Su padre Publicola fue un Senador de Roma.<br \/>\nSe uni\u00f3 en matrimonio con Piniano y se convirti\u00f3 en madre de dos hijos, los cuales perdi\u00f3 poco despu\u00e9s. Por lo tanto, habiendo acordado con su esposo pasar el resto de sus vidas en abstinencia y castidad, y llevando a su madre Albina con ella, se fue a \u00c1frica. Rescataron a 8,000 cautivos; Adem\u00e1s, construyeron dos monasterios, uno para hombres y otro para mujeres, en la ciudad de Tagaste, en el distrito de T\u00fanez. Despu\u00e9s de siete a\u00f1os se mudaron a Jerusal\u00e9n. A los catorce a\u00f1os de residir en Palestina, muri\u00f3 Albina y, al a\u00f1o siguiente, Piniano la sigui\u00f3 a la tumba. Melania sepult\u00f3 a su esposo al lado de su madre en el Monte de los Olivos y se construy\u00f3 una celda cerca de las tumbas de sus fieles compa\u00f1eros. La celda fue el n\u00facleo de un amplio convento de v\u00edrgenes consagradas que presidi\u00f3 Santa Melania. A partir de entonces, Melania se encerr\u00f3 en una peque\u00f1a y estrecha ermita junto al Monte de los Olivos, y desgastando su cuerpo con ayunos y vigilias, descans\u00f3 el a\u00f1o 434.<br \/>\nComo este d\u00eda se celebra la Despedida de la Navidad, los himnos propios de santa Melania, se han fusionado con los de santa Anisia celebrada ayer.<\/p>\n<p>Tropario com\u00fan de los mon\u00e1sticos, tono 4<br \/>\nEn ti fue conservada la imagen de Dios fielmente, oh Madre pues tomando la cruz seguiste a Cristo; y practicando, ense\u00f1aste a despreocuparse de la carne, que es ef\u00edmera, y a cuidar, en cambio, el alma inmortal. Por eso hoy tu esp\u00edritu se regocija Venerable Melania junto con los \u00e1ngeles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santa Melania la Joven, de Roma. 31 de Diciembre Santa Melania la Joven, que naci\u00f3 en 388, era la nieta de Santa Melania la Grande (8 de junio). Su padre Publicola fue un Senador de Roma. Se uni\u00f3 en matrimonio con Piniano y se convirti\u00f3 en madre de dos hijos, los cuales perdi\u00f3 poco despu\u00e9s. [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"categories":[108,16],"tags":[],"_links":{"self":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts\/15532"}],"collection":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/comments?post=15532"}],"version-history":[{"count":2,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts\/15532\/revisions"}],"predecessor-version":[{"id":15656,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/posts\/15532\/revisions\/15656"}],"wp:attachment":[{"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/media?parent=15532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/categories?post=15532"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/iglesiaortodoxa.org.mx\/informacion\/wp-json\/wp\/v2\/tags?post=15532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}